{"id":43,"count":2,"description":"","link":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/","name":"Medien","slug":"medien","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medien Archive - Gewerbeverein Oberes Fricktal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medien Archive - Gewerbeverein Oberes Fricktal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/\" \/>\n<meta property=\"og:site_name\" content=\"Gewerbeverein Oberes Fricktal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/index.php\\\/tag\\\/medien\\\/\",\"url\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/index.php\\\/tag\\\/medien\\\/\",\"name\":\"Medien Archive - Gewerbeverein Oberes Fricktal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/index.php\\\/tag\\\/medien\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/index.php\\\/tag\\\/medien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/#website\",\"url\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/\",\"name\":\"Gewerbeverein Oberes Fricktal\",\"description\":\"Ein starkes Gewerbe braucht die Region.\",\"publisher\":{\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/#organization\",\"name\":\"Gewerbeverein Oberes Fricktal\",\"url\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/GOF_Wortmarke-DEF_positiv-gruen-anthrazit_ausschnitt.jpg\",\"contentUrl\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/GOF_Wortmarke-DEF_positiv-gruen-anthrazit_ausschnitt.jpg\",\"width\":1214,\"height\":498,\"caption\":\"Gewerbeverein Oberes Fricktal\"},\"image\":{\"@id\":\"https:\\\/\\\/gewerbeoberesfricktal.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/gewerbe-oberes-fricktal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medien Archive - Gewerbeverein Oberes Fricktal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/","og_locale":"de_DE","og_type":"article","og_title":"Medien Archive - Gewerbeverein Oberes Fricktal","og_url":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/","og_site_name":"Gewerbeverein Oberes Fricktal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/","url":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/","name":"Medien Archive - Gewerbeverein Oberes Fricktal","isPartOf":{"@id":"https:\/\/gewerbeoberesfricktal.ch\/#website"},"breadcrumb":{"@id":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/#breadcrumb"},"inLanguage":"de-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/tag\/medien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gewerbeoberesfricktal.ch\/"},{"@type":"ListItem","position":2,"name":"Medien"}]},{"@type":"WebSite","@id":"https:\/\/gewerbeoberesfricktal.ch\/#website","url":"https:\/\/gewerbeoberesfricktal.ch\/","name":"Gewerbeverein Oberes Fricktal","description":"Ein starkes Gewerbe braucht die Region.","publisher":{"@id":"https:\/\/gewerbeoberesfricktal.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gewerbeoberesfricktal.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/gewerbeoberesfricktal.ch\/#organization","name":"Gewerbeverein Oberes Fricktal","url":"https:\/\/gewerbeoberesfricktal.ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/gewerbeoberesfricktal.ch\/#\/schema\/logo\/image\/","url":"https:\/\/gewerbeoberesfricktal.ch\/wp-content\/uploads\/2018\/04\/GOF_Wortmarke-DEF_positiv-gruen-anthrazit_ausschnitt.jpg","contentUrl":"https:\/\/gewerbeoberesfricktal.ch\/wp-content\/uploads\/2018\/04\/GOF_Wortmarke-DEF_positiv-gruen-anthrazit_ausschnitt.jpg","width":1214,"height":498,"caption":"Gewerbeverein Oberes Fricktal"},"image":{"@id":"https:\/\/gewerbeoberesfricktal.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/gewerbe-oberes-fricktal"]}]}},"_links":{"self":[{"href":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/wp-json\/wp\/v2\/tags\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gewerbeoberesfricktal.ch\/index.php\/wp-json\/wp\/v2\/posts?tags=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}